{"id":162221,"date":"2021-10-14T15:34:49","date_gmt":"2021-10-14T18:34:49","guid":{"rendered":"https:\/\/design.novoambiente.com\/produto\/woven-chair\/"},"modified":"2021-10-14T15:34:49","modified_gmt":"2021-10-14T18:34:49","slug":"woven-chair","status":"publish","type":"product","link":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/","title":{"rendered":"Woven Chair"},"content":{"rendered":"<p>Lets the wind pass through, ventilate, aerate\u2014a poetry written in curves, without right angles. The junction of tubes that extends from the arms and forms the legs in an aerodynamic gesture opens up to outline the backrest. <\/p>\n","protected":false},"excerpt":{"rendered":"Lets the wind pass through, ventilate, aerate\u2014a poetry written in curves, without right angles. The junction of&#8230;","protected":false},"featured_media":141340,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3418,3428],"product_tag":[],"colecao":[3674],"3d":[3462],"class_list":["post-162221","product","type-product","status-publish","has-post-thumbnail","product_cat-outdoor-area","product_cat-armchairs","pa_designer-rejane-carvalho-leite","colecao-dona-flor","3d-arquivos-3d","first","instock","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Woven Chair - Novo Ambiente | Cat\u00e1logo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/\",\"name\":\"Woven Chair - Novo Ambiente | Cat\u00e1logo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/758A9909-scaled-650x975-1-1.jpg\",\"datePublished\":\"2021-10-14T18:34:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/#primaryimage\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/758A9909-scaled-650x975-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/758A9909-scaled-650x975-1-1.jpg\",\"width\":650,\"height\":975},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/woven-chair\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Furniture\",\"item\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/furniture\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Woven Chair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/\",\"name\":\"Novo Ambiente | Mobili\u00e1rio\",\"description\":\"Mobili\u00e1rio de design para casa ou escrit\u00f3rio\",\"publisher\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#organization\",\"name\":\"Novo Ambiente | Mobili\u00e1rio\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_NA_SP.jpg\",\"contentUrl\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_NA_SP.jpg\",\"width\":1709,\"height\":1742,\"caption\":\"Novo Ambiente | Mobili\u00e1rio\"},\"image\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LojaNovoAmbiente\",\"https:\\\/\\\/www.instagram.com\\\/novoambiente\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Woven Chair - Novo Ambiente | Cat\u00e1logo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/","url":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/","name":"Woven Chair - Novo Ambiente | Cat\u00e1logo","isPartOf":{"@id":"https:\/\/design.novoambiente.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/#primaryimage"},"image":{"@id":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/#primaryimage"},"thumbnailUrl":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2021\/10\/758A9909-scaled-650x975-1-1.jpg","datePublished":"2021-10-14T18:34:49+00:00","breadcrumb":{"@id":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/#primaryimage","url":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2021\/10\/758A9909-scaled-650x975-1-1.jpg","contentUrl":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2021\/10\/758A9909-scaled-650x975-1-1.jpg","width":650,"height":975},{"@type":"BreadcrumbList","@id":"https:\/\/design.novoambiente.com\/en\/product\/woven-chair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/design.novoambiente.com\/en\/"},{"@type":"ListItem","position":2,"name":"Furniture","item":"https:\/\/design.novoambiente.com\/en\/furniture\/"},{"@type":"ListItem","position":3,"name":"Woven Chair"}]},{"@type":"WebSite","@id":"https:\/\/design.novoambiente.com\/en\/#website","url":"https:\/\/design.novoambiente.com\/en\/","name":"Novo Ambiente | Mobili\u00e1rio","description":"Mobili\u00e1rio de design para casa ou escrit\u00f3rio","publisher":{"@id":"https:\/\/design.novoambiente.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/design.novoambiente.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/design.novoambiente.com\/en\/#organization","name":"Novo Ambiente | Mobili\u00e1rio","url":"https:\/\/design.novoambiente.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/design.novoambiente.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2026\/06\/logo_NA_SP.jpg","contentUrl":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2026\/06\/logo_NA_SP.jpg","width":1709,"height":1742,"caption":"Novo Ambiente | Mobili\u00e1rio"},"image":{"@id":"https:\/\/design.novoambiente.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LojaNovoAmbiente","https:\/\/www.instagram.com\/novoambiente"]}]}},"_links":{"self":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product\/162221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/media\/141340"}],"wp:attachment":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/media?parent=162221"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product_brand?post=162221"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product_cat?post=162221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product_tag?post=162221"},{"taxonomy":"colecao","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/colecao?post=162221"},{"taxonomy":"3d","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/3d?post=162221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}