{"id":159470,"date":"2023-06-13T11:31:35","date_gmt":"2023-06-13T14:31:35","guid":{"rendered":"https:\/\/design.novoambiente.com\/produto\/zig-zag-buffet\/"},"modified":"2023-06-13T11:31:35","modified_gmt":"2023-06-13T14:31:35","slug":"zig-zag-buffet","status":"publish","type":"product","link":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/","title":{"rendered":"Zig Zag Buffet"},"content":{"rendered":"<p><strong>Available for sale only in S\u00e3o Paulo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Available for sale only in S\u00e3o Paulo","protected":false},"featured_media":197850,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3400,3404],"product_tag":[],"colecao":[],"3d":[3462],"class_list":["post-159470","product","type-product","status-publish","has-post-thumbnail","product_cat-indoor-area","product_cat-sideboard","pa_designer-leo-romano","3d-arquivos-3d","first","instock","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zig Zag Buffet - Novo Ambiente | Cat\u00e1logo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/\",\"name\":\"Zig Zag Buffet - Novo Ambiente | Cat\u00e1logo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-de-tela-2026-04-17-150040.png\",\"datePublished\":\"2023-06-13T14:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-de-tela-2026-04-17-150040.png\",\"contentUrl\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Captura-de-tela-2026-04-17-150040.png\",\"width\":723,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/product\\\/zig-zag-buffet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Furniture\",\"item\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/furniture\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zig Zag Buffet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/\",\"name\":\"Novo Ambiente | Mobili\u00e1rio\",\"description\":\"Mobili\u00e1rio de design para casa ou escrit\u00f3rio\",\"publisher\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#organization\",\"name\":\"Novo Ambiente | Mobili\u00e1rio\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_NA_SP.jpg\",\"contentUrl\":\"https:\\\/\\\/design.novoambiente.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_NA_SP.jpg\",\"width\":1709,\"height\":1742,\"caption\":\"Novo Ambiente | Mobili\u00e1rio\"},\"image\":{\"@id\":\"https:\\\/\\\/design.novoambiente.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LojaNovoAmbiente\",\"https:\\\/\\\/www.instagram.com\\\/novoambiente\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zig Zag Buffet - Novo Ambiente | Cat\u00e1logo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/","url":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/","name":"Zig Zag Buffet - Novo Ambiente | Cat\u00e1logo","isPartOf":{"@id":"https:\/\/design.novoambiente.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/#primaryimage"},"image":{"@id":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/#primaryimage"},"thumbnailUrl":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2023\/06\/Captura-de-tela-2026-04-17-150040.png","datePublished":"2023-06-13T14:31:35+00:00","breadcrumb":{"@id":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/#primaryimage","url":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2023\/06\/Captura-de-tela-2026-04-17-150040.png","contentUrl":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2023\/06\/Captura-de-tela-2026-04-17-150040.png","width":723,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/design.novoambiente.com\/en\/product\/zig-zag-buffet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/design.novoambiente.com\/en\/"},{"@type":"ListItem","position":2,"name":"Furniture","item":"https:\/\/design.novoambiente.com\/en\/furniture\/"},{"@type":"ListItem","position":3,"name":"Zig Zag Buffet"}]},{"@type":"WebSite","@id":"https:\/\/design.novoambiente.com\/en\/#website","url":"https:\/\/design.novoambiente.com\/en\/","name":"Novo Ambiente | Mobili\u00e1rio","description":"Mobili\u00e1rio de design para casa ou escrit\u00f3rio","publisher":{"@id":"https:\/\/design.novoambiente.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/design.novoambiente.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/design.novoambiente.com\/en\/#organization","name":"Novo Ambiente | Mobili\u00e1rio","url":"https:\/\/design.novoambiente.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/design.novoambiente.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2026\/06\/logo_NA_SP.jpg","contentUrl":"https:\/\/design.novoambiente.com\/wp-content\/uploads\/2026\/06\/logo_NA_SP.jpg","width":1709,"height":1742,"caption":"Novo Ambiente | Mobili\u00e1rio"},"image":{"@id":"https:\/\/design.novoambiente.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LojaNovoAmbiente","https:\/\/www.instagram.com\/novoambiente"]}]}},"_links":{"self":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product\/159470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/media\/197850"}],"wp:attachment":[{"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/media?parent=159470"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product_brand?post=159470"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product_cat?post=159470"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/product_tag?post=159470"},{"taxonomy":"colecao","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/colecao?post=159470"},{"taxonomy":"3d","embeddable":true,"href":"https:\/\/design.novoambiente.com\/en\/wp-json\/wp\/v2\/3d?post=159470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}